{"id":883,"date":"2015-11-08T01:57:01","date_gmt":"2015-11-08T01:57:01","guid":{"rendered":"http:\/\/fasaststcs.com\/?page_id=883"},"modified":"2022-01-02T17:21:03","modified_gmt":"2022-01-02T17:21:03","slug":"r-9-stellarhawk-class-vi-escort","status":"publish","type":"page","link":"https:\/\/fasaststcs.com\/index.php\/thefleets\/romulan-star-empire\/r-9-stellarhawk-class-vi-escort\/","title":{"rendered":"SKE (Stellarhawk) Class VI Escort"},"content":{"rendered":"<h6>\u00abLast Updated &#8211; November 7, 2015\u00bb<\/h6>\n<hr noshade=\"noshade\" size=\"5\" \/>\n<a href=\"https:\/\/fasaststcs.com\/wp-content\/uploads\/2015\/11\/romulan_r9.jpg\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/fasaststcs.com\/wp-content\/uploads\/2015\/11\/romulan_r9.jpg\" alt=\"romulan_r9\" width=\"450\" height=\"529\" class=\"aligncenter size-full wp-image-884\" srcset=\"https:\/\/fasaststcs.com\/wp-content\/uploads\/2015\/11\/romulan_r9.jpg 450w, https:\/\/fasaststcs.com\/wp-content\/uploads\/2015\/11\/romulan_r9-255x300.jpg 255w\" sizes=\"auto, (max-width: 450px) 100vw, 450px\" \/><\/a><\/p>\n<h6>Design\/concept by SFB Amerillo Design Bureau, SFC conversion by Interplay\/ 14East, Taldren<\/h6>\n<hr noshade=\"noshade\" size=\"5\" \/>\n<h5>Known Sphere Of Operation: Empire-wide<br \/>\nData Reliability: D for Type-1<br \/>\nMajor Data Source: Operation Grey Ghost<\/h5>\n<p><strong>NOTES:<\/strong><\/p>\n<hr noshade=\"noshade\" size=\"5\" \/>\n<table border=\"0\" cellspacing=\"0\" cellpadding=\"0\" align=\"center\">\n<tr>\n<td class=\"ship\" style=\"width: 280px;\"><strong>Construction Data:<\/strong><\/td>\n<td class=\"ship\" style=\"width: 250px;\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Model &#8211;<\/td>\n<td class=\"ship\">Type-1<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Ship Class &#8211;<\/td>\n<td class=\"ship\">VI<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Date Entering Service &#8211;<\/td>\n<td class=\"ship\">2273<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Number Constructed &#8211;<\/td>\n<td class=\"ship\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\"><strong>Hull Data:<\/strong><\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Superstructure Points &#8211;<\/td>\n<td class=\"ship\">20<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Damage Chart &#8211;<\/td>\n<td class=\"ship\">C<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Size:<\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00a0Length &#8211;<\/td>\n<td class=\"ship\">114 m<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Width &#8211;<\/td>\n<td class=\"ship\">71 m<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Height &#8211;<\/td>\n<td class=\"ship\">24 m<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Weight &#8211;<\/td>\n<td class=\"ship\">71,040 mt<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Cargo:<\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Total SCU &#8211;<\/td>\n<td class=\"ship\">120 SCU<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Cargo Capacity &#8211;<\/td>\n<td class=\"ship\">6,000 mt<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Landing Capacity &#8211;<\/td>\n<td class=\"ship\">None<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\"><strong>Equipment Date:<\/strong><\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Control Computer Type &#8211;<\/td>\n<td class=\"ship\">R-5M<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Transporters:<\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Standard 9-person &#8211;<\/td>\n<td class=\"ship\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Emergency 20-person &#8211;<\/td>\n<td class=\"ship\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Cargo &#8211;<\/td>\n<td class=\"ship\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Cloaking Decive Type &#8211;<\/td>\n<td class=\"ship\">RCC<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Power Requirement &#8211;<\/td>\n<td class=\"ship\">15<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\"><strong>Other Data:<\/strong><\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Crew &#8211;<\/td>\n<td class=\"ship\">130<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Passengers &#8211;<\/td>\n<td class=\"ship\">30<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Shuttlecraft &#8211;<\/td>\n<td class=\"ship\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\"><strong>Engines And Power Data:<\/strong><\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Total Power Units Available &#8211;<\/td>\n<td class=\"ship\">30<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Movement Point Ratio &#8211;<\/td>\n<td class=\"ship\">2\/1<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Warp Engine Type &#8211;<\/td>\n<td class=\"ship\">RWD-2<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Number &#8211;<\/td>\n<td class=\"ship\">1<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Power Units Available &#8211;<\/td>\n<td class=\"ship\">18<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Stress Chart &#8211;<\/td>\n<td class=\"ship\">O\/Q<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Max Safe Cruising Speed &#8211;<\/td>\n<td class=\"ship\">Warp 7<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Emergency Speed &#8211;<\/td>\n<td class=\"ship\">Warp 8<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Impulse Engine Type &#8211;<\/td>\n<td class=\"ship\">RID-3<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Power Units Available &#8211;<\/td>\n<td class=\"ship\">12<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\"><strong>Weapons And Firing Data:<\/strong><\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Beam Weapon Type &#8211;<\/td>\n<td class=\"ship\">RB-9<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Number &#8211;<\/td>\n<td class=\"ship\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Firing Arcs &#8211;<\/td>\n<td class=\"ship\">2 p\/f\/s, 1 f\/p, 1 f\/s<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Firing Chart &#8211;<\/td>\n<td class=\"ship\">W<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Maximum Power &#8211;<\/td>\n<td class=\"ship\">6<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Damage Modifiers:<\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;+3<\/td>\n<td class=\"ship\">(1-8)<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;+2<\/td>\n<td class=\"ship\">(9-16)<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;+1<\/td>\n<td class=\"ship\">(17-20<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Beam Weapon Type &#8211;<\/td>\n<td class=\"ship\">RB-2a<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Number &#8211;<\/td>\n<td class=\"ship\">4<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;\u00a0Firing Arcs &#8211;<\/td>\n<td class=\"ship\">2 f\/p\/a, 2 f\/s\/a<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Firing Chart &#8211;<\/td>\n<td class=\"ship\">K<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Maximum Power &#8211;<\/td>\n<td class=\"ship\">3<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Damage Modifiers:<\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;+3<\/td>\n<td class=\"ship\">(1-4)<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;+2<\/td>\n<td class=\"ship\">(5-9)<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;+1<\/td>\n<td class=\"ship\">(10-14)<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Torpedo Weapon Type &#8211;<\/td>\n<td class=\"ship\">RPL-1<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Number\u00a0&#8211;<\/td>\n<td class=\"ship\">2<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Firing Arcs\u00a0&#8211;<\/td>\n<td class=\"ship\">2 f<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; Firing Chart\u00a0&#8211;<\/td>\n<td class=\"ship\">E<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Power to Arm\u00a0&#8211;<\/td>\n<td class=\"ship\">10<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Damage\u00a0&#8211;<\/td>\n<td class=\"ship\">RL-1<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\"><strong>Shield Data:<\/strong><\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Deflector Shield Type &#8211;<\/td>\n<td class=\"ship\">RSI<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Shield Point Ratio &#8211;<\/td>\n<td class=\"ship\">1\/3<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Maximum Shield Power &#8211;<\/td>\n<td class=\"ship\">14<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\"><strong>Combat Efficiency:<\/strong><\/td>\n<td class=\"ship\"><\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;D &#8211;<\/td>\n<td class=\"ship\">112.6<\/td>\n<\/tr>\n<tr>\n<td class=\"ship\">&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;WDF &#8211;<\/td>\n<td class=\"ship\">42.2<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>\u00abLast Updated &#8211; November 7, 2015\u00bb Design\/concept by SFB Amerillo Design Bureau, SFC conversion by Interplay\/ 14East, Taldren Known Sphere Of Operation: Empire-wide Data Reliability: D for Type-1 Major Data Source: Operation Grey Ghost NOTES: Construction Data: &nbsp;&nbsp;&nbsp;&nbsp;&nbsp;Model &#8211; Type-1&hellip; <a href=\"https:\/\/fasaststcs.com\/index.php\/thefleets\/romulan-star-empire\/r-9-stellarhawk-class-vi-escort\/\" class=\"more-link\">Continue Reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":15,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-template-full.php","meta":{"footnotes":""},"class_list":["post-883","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/fasaststcs.com\/index.php\/wp-json\/wp\/v2\/pages\/883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fasaststcs.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fasaststcs.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fasaststcs.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/fasaststcs.com\/index.php\/wp-json\/wp\/v2\/comments?post=883"}],"version-history":[{"count":4,"href":"https:\/\/fasaststcs.com\/index.php\/wp-json\/wp\/v2\/pages\/883\/revisions"}],"predecessor-version":[{"id":8429,"href":"https:\/\/fasaststcs.com\/index.php\/wp-json\/wp\/v2\/pages\/883\/revisions\/8429"}],"up":[{"embeddable":true,"href":"https:\/\/fasaststcs.com\/index.php\/wp-json\/wp\/v2\/pages\/15"}],"wp:attachment":[{"href":"https:\/\/fasaststcs.com\/index.php\/wp-json\/wp\/v2\/media?parent=883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}